{"id":46955,"date":"2026-07-15T10:35:54","date_gmt":"2026-07-15T13:35:54","guid":{"rendered":"http:\/\/eenergetica.com.ar\/?p=46955"},"modified":"2026-07-15T10:35:55","modified_gmt":"2026-07-15T13:35:55","slug":"pese-a-los-esfuerzos-el-gobierno-no-logra-retomar-la-actividad-los-factores-que-empanan-los-planes","status":"publish","type":"post","link":"https:\/\/eenergetica.com.ar\/index.php\/2026\/07\/15\/pese-a-los-esfuerzos-el-gobierno-no-logra-retomar-la-actividad-los-factores-que-empanan-los-planes\/","title":{"rendered":"Pese a los esfuerzos, el Gobierno no logra retomar la actividad: los factores que empa\u00f1an los planes"},"content":{"rendered":"\n<p>Con&nbsp;<strong>Manuel Adorni<\/strong>&nbsp;fuera de escena, el Gobierno Nacional hace sobrados esfuerzos por recuperar la actividad con importante eje en la agenda legislativa, pero&nbsp;<strong>diversos factores complejizan el objetivo final.&nbsp;<\/strong><\/p>\n\n\n\n<p>La mesa pol\u00edtica se reuni\u00f3 el pasado martes para intentar ordenar el listado de reformas que el Poder Ejecutivo defini\u00f3 como prioritarias, con intenci\u00f3n de retomar la iniciativa que perdi\u00f3 a ra\u00edz de la causa abierta por<strong>&nbsp;presunto enriquecimiento il\u00edcito&nbsp;<\/strong>contra el exjefe de Gabinete.&nbsp;<\/p>\n\n\n\n<p>Tras la salida del funcionario, en Casa Rosada se e<strong>speranzaban con reencausar la gesti\u00f3n&nbsp;<\/strong>a trav\u00e9s de la actividad en el Congreso Nacional. Sin embargo, el&nbsp;<strong>receso invernal<\/strong>&nbsp;que inicar\u00e1 la pr\u00f3xima semana hasta agosto complejiza los planes.&nbsp;<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de las vacaciones de los legisladores, el oficialismo se enfrenta a un escenario a\u00fan m\u00e1s complejo:<strong>&nbsp;la falta de apoyos de los aliados<\/strong>&nbsp;a los distintos proyectos de ley que enviaron al Congreso.&nbsp;<\/p>\n\n\n\n<p>Durante la primera reuni\u00f3n que mantuvo el presidente Javier Milei con legisladores estableci\u00f3 las claves de los pr\u00f3ximos d\u00edas que giran en torno a la modificaci\u00f3n del proyecto de&nbsp;<strong>Zonas Fr\u00edas,<\/strong>&nbsp;a los cambios en la normativa de&nbsp;<strong>Inocencia Fiscal&nbsp;<\/strong>y a&nbsp;<strong>la reforma electoral.&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con&nbsp;Manuel Adorni&nbsp;fuera de escena, el Gobierno Nacional hace sobrados esfuerzos por recuperar la actividad con importante eje en la agenda legislativa, pero&nbsp;diversos factores complejizan el objetivo final.&nbsp; La mesa pol\u00edtica&hellip; <\/p>\n","protected":false},"author":2,"featured_media":46956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,20],"tags":[],"class_list":["post-46955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-politica"],"_links":{"self":[{"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=46955"}],"version-history":[{"count":1,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46955\/revisions"}],"predecessor-version":[{"id":46957,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/46955\/revisions\/46957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/media\/46956"}],"wp:attachment":[{"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=46955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=46955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eenergetica.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=46955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}